{"id":632,"name":"Eva M\u00aa Gonz\u00e1lez P\u00e9rez","url":"","description":"","link":"https:\/\/ufasu.blogs.upv.es\/es\/author\/egonzal\/","slug":"egonzal","meta":[],"_links":{"self":[{"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/users\/632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/users"}]}}