{"id":37,"date":"2015-01-08T10:00:19","date_gmt":"2015-01-08T09:00:19","guid":{"rendered":"http:\/\/ufasu.blogs.upv.es\/?p=37"},"modified":"2015-01-08T10:05:01","modified_gmt":"2015-01-08T09:05:01","slug":"biblioteca-materiales","status":"publish","type":"post","link":"https:\/\/ufasu.blogs.upv.es\/es\/biblioteca-materiales\/","title":{"rendered":"Biblioteca de materiales de formaci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"http:\/\/ufasu.blogs.upv.es\/wp-content\/uploads\/2013\/07\/79721_4362.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-98 alignleft\" src=\"http:\/\/ufasu.blogs.upv.es\/wp-content\/uploads\/2013\/07\/79721_4362-300x200.jpg\" alt=\"79721_4362\" width=\"210\" height=\"140\" srcset=\"https:\/\/ufasu.blogs.upv.es\/wp-content\/uploads\/2013\/07\/79721_4362-300x200.jpg 300w, https:\/\/ufasu.blogs.upv.es\/wp-content\/uploads\/2013\/07\/79721_4362-700x466.jpg 700w, https:\/\/ufasu.blogs.upv.es\/wp-content\/uploads\/2013\/07\/79721_4362.jpg 720w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a>Los usuarios de la Unidad de Formaci\u00f3n del PAS \u00a0disponen en el <strong>Portal de Formaci\u00f3n de la UPV<\/strong>, de una funcionalidad que les permite acceder a todos los materiales que facilitamos a los alumnos de los cursos principalmente presenciales.<\/p>\r\n<p style=\"text-align: justify\">En el Portal de Formaci\u00f3n, dentro de las diferentes actividades de formaci\u00f3n donde has sido aceptado, dispones de una pesta\u00f1a de <em>materiales<\/em> desde donde encontrar los <strong>contenidos de los cursos en formato digital<\/strong> (ppt, pdf, doc, jpg, etc)<\/p>\r\n<p style=\"text-align: justify\">Estos materiales est\u00e1n disponibles desde el a\u00f1o 2011 y <strong>se mantendr\u00e1n de manera permanente<\/strong>\u00a0permitiendo acceder a los documentos cuando el usuario requiera consultarlos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los usuarios de la Unidad de Formaci\u00f3n del PAS \u00a0disponen en el Portal de Formaci\u00f3n de la UPV, de una funcionalidad que les permite acceder a todos los materiales que facilitamos a los alumnos de los cursos principalmente presenciales. En el Portal de Formaci\u00f3n, dentro de las diferentes actividades de &#8230;<\/p>\n","protected":false},"author":632,"featured_media":38,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[102787],"tags":[158413,217,102789,810,158534],"class_list":["post-37","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-portal-de-formacion","tag-biblioteca-ufasu","tag-formacion","tag-formacion-empleados","tag-materiales","tag-portal-de-formacion","post_format-post-format-image"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/posts\/37","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/users\/632"}],"replies":[{"embeddable":true,"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":0,"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/posts\/37\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/media\/38"}],"wp:attachment":[{"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/media?parent=37"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/categories?post=37"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ufasu.blogs.upv.es\/es\/wp-json\/wp\/v2\/tags?post=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}